{"id":7110,"date":"2022-01-24T17:03:49","date_gmt":"2022-01-24T15:03:49","guid":{"rendered":"https:\/\/xoompoint.kajahdusdev.fi\/sisallontuotannon-tyokalut"},"modified":"2023-10-18T16:29:28","modified_gmt":"2023-10-18T13:29:28","slug":"content-production-tools","status":"publish","type":"page","link":"https:\/\/xoompoint.com\/en\/content-production-tools","title":{"rendered":"Content production tools"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;10px&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;reverse&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#edede1&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; bottom_padding=&#8221;18%&#8221; left_padding_desktop=&#8221;5%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5%&#8221; bottom_padding_tablet=&#8221;20%&#8221; bottom_padding_phone=&#8221;30%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#ffffff&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;100&#8243; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;tilt_alt&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;parallax&#8221; animation_movement_type=&#8221;transform_x&#8221; column_parallax_intensity=&#8221;1&#8243; persist_movement_on_mobile=&#8221;true&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Content production tools&#8221; font_container=&#8221;tag:h1|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_custom_heading text=&#8221;Produce content in an agile way with H5P tools&#8221; font_container=&#8221;tag:h4|text_align:left|color:%23505a64&#8243; use_theme_fonts=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;5%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5%&#8221; left_padding_tablet=&#8221;0&#8243; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;0&#8243; left_padding_phone=&#8221;0&#8243; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;-22%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;left&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;small_depth&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; zindex=&#8221;-99&#8243; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;What needs do you have for e-learning content?&#8221; font_container=&#8221;tag:h2|text_align:center|color:%23505a64&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_row_inner column_margin=&#8221;40px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;3%&#8221; left_padding_desktop=&#8221;5%&#8221; left_padding_tablet=&#8221;0&#8243; left_padding_phone=&#8221;0&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]<strong>H5P<\/strong> is a browser-based content production tool that you can use to create various online training materials, interactive exercises, games, quizzes and other interactive elements. <strong>H5P<\/strong> is integrated with FlowLMS and available to FlowLMS customers.<\/p>\n<p>If you want to use existing PowerPoint presentations and take them to the next level, iSpring Suite\u00a0is the right tool for you. You can use it to add simulations, a wide range of tasks, and interactive pictures and diagrams to your presentations.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin_tablet=&#8221;3%&#8221; top_margin_phone=&#8221;5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]The courses you create are seamlessly browsable on any terminal device your learners use.<\/p>\n<p>We can train you in how to effectively use content production tools, whether you choose H5P (a content production tool built in to the core of the FlowLMS e-learning environment) or iSpring Suite.<\/p>\n<p>To support your content production, we can provide you with e-learning templates featuring your company\u2019s branding to make it extremely easy to make e-learning courses.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;default_arrow&#8221; text=&#8221;Book a presentation&#8221; margin_right=&#8221;15&#8243; url=&#8221;#contact&#8221;][nectar_btn size=&#8221;large&#8221; button_style=&#8221;see-through&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;default_arrow&#8221; text=&#8221;Contact us&#8221; margin_right=&#8221;15&#8243; url=&#8221;\/en\/contact-us#contact&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;3%&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;right&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;contact&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#dd6e42&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;60px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#ffffff&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Send us your contact details or book a presentation&#8221; font_container=&#8221;tag:h3|font_size:5vh|text_align:left|color:%23ffffff|line_height:6vh&#8221; use_theme_fonts=&#8221;yes&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][vc_custom_heading text=&#8221;We are happy to tell you more about these fantastic tools.&#8221; font_container=&#8221;tag:p|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"wpforms-container wpforms-container-full formpika\" id=\"wpforms-7197\"><form id=\"wpforms-form-7197\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"7197\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/7110\" data-token=\"cc6cb3abba32204cc7e27cd6be1e33b2\" data-token-time=\"1778694556\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-7197-field_1-container\" class=\"wpforms-field wpforms-field-name wpforms-one-half wpforms-first wpforms-mobile-full\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-7197-field_1\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-7197-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"Name *\" required><\/div><div id=\"wpforms-7197-field_2-container\" class=\"wpforms-field wpforms-field-phone wpforms-one-half wpforms-mobile-full\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-7197-field_2\">Telephone number<\/label><input type=\"tel\" id=\"wpforms-7197-field_2\" class=\"wpforms-field-large wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][2]\" placeholder=\"40 123 4567\" aria-label=\"Telephone number\" ><\/div><div id=\"wpforms-7197-field_3-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"3\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-7197-field_3\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-7197-field_3\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][3]\" placeholder=\"E-mail address *\" spellcheck=\"false\" required><\/div><div id=\"wpforms-7197-field_4-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"4\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-7197-field_4\">Message<\/label><textarea id=\"wpforms-7197-field_4\" class=\"wpforms-field-small\" name=\"wpforms[fields][4]\" placeholder=\"How can we help you?\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v2\" ><div class=\"g-recaptcha\" data-sitekey=\"6Ld38CokAAAAALyAuH5_19sLguvHnMvJR9Uz974N\"><\/div><input type=\"text\" name=\"g-recaptcha-hidden\" class=\"wpforms-recaptcha-hidden\" style=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\" data-rule-recaptcha=\"1\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"7197\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/xoompoint.com\/en\/wp-json\/wp\/v2\/pages\/7110\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-7197\" class=\"wpforms-submit sendpika\" data-alt-text=\"Sending...\" data-submit-text=\"Send\" aria-live=\"assertive\" value=\"wpforms-submit\">Send<\/button><img decoding=\"async\" src=\"https:\/\/xoompoint.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;10px&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;reverse&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#edede1&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; bottom_padding=&#8221;18%&#8221; left_padding_desktop=&#8221;5%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5%&#8221; bottom_padding_tablet=&#8221;20%&#8221; bottom_padding_phone=&#8221;30%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243;&#8230;<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7110","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Content production tools - Xoompoint<\/title>\n<meta name=\"description\" content=\"Produce e-lerning content in an agile way with H5P tools. Book a presentation!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xoompoint.com\/en\/content-production-tools\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Content production tools - Xoompoint\" \/>\n<meta property=\"og:description\" content=\"Produce e-lerning content in an agile way with H5P tools. Book a presentation!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xoompoint.com\/en\/content-production-tools\" \/>\n<meta property=\"og:site_name\" content=\"Xoompoint\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-18T13:29:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xoompoint.com\/wp-content\/uploads\/2024\/01\/Tavoitteena-osaamisen-johtaminen-ja-koko-tyon-kehittaminen.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xoompoint.com\\\/en\\\/content-production-tools\",\"url\":\"https:\\\/\\\/xoompoint.com\\\/en\\\/content-production-tools\",\"name\":\"Content production tools - Xoompoint\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xoompoint.com\\\/#website\"},\"datePublished\":\"2022-01-24T15:03:49+00:00\",\"dateModified\":\"2023-10-18T13:29:28+00:00\",\"description\":\"Produce e-lerning content in an agile way with H5P tools. Book a presentation!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xoompoint.com\\\/en\\\/content-production-tools#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xoompoint.com\\\/en\\\/content-production-tools\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xoompoint.com\\\/en\\\/content-production-tools#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/xoompoint.com\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Content production tools\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xoompoint.com\\\/#website\",\"url\":\"https:\\\/\\\/xoompoint.com\\\/\",\"name\":\"Xoompoint\",\"description\":\"Kaikki, mit\u00e4 tarvitset digioppimiseen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/xoompoint.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xoompoint.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/xoompoint.com\\\/#organization\",\"name\":\"Xoompoint Oy\",\"url\":\"https:\\\/\\\/xoompoint.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/xoompoint.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/xoompoint.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/xoompoint-logo-black_800px.png\",\"contentUrl\":\"https:\\\/\\\/xoompoint.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/xoompoint-logo-black_800px.png\",\"width\":800,\"height\":138,\"caption\":\"Xoompoint Oy\"},\"image\":{\"@id\":\"https:\\\/\\\/xoompoint.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/xoompoint\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/xoompoint-corporation\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Content production tools - Xoompoint","description":"Produce e-lerning content in an agile way with H5P tools. Book a presentation!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xoompoint.com\/en\/content-production-tools","og_locale":"en_US","og_type":"article","og_title":"Content production tools - Xoompoint","og_description":"Produce e-lerning content in an agile way with H5P tools. Book a presentation!","og_url":"https:\/\/xoompoint.com\/en\/content-production-tools","og_site_name":"Xoompoint","article_modified_time":"2023-10-18T13:29:28+00:00","og_image":[{"width":1100,"height":750,"url":"https:\/\/xoompoint.com\/wp-content\/uploads\/2024\/01\/Tavoitteena-osaamisen-johtaminen-ja-koko-tyon-kehittaminen.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xoompoint.com\/en\/content-production-tools","url":"https:\/\/xoompoint.com\/en\/content-production-tools","name":"Content production tools - Xoompoint","isPartOf":{"@id":"https:\/\/xoompoint.com\/#website"},"datePublished":"2022-01-24T15:03:49+00:00","dateModified":"2023-10-18T13:29:28+00:00","description":"Produce e-lerning content in an agile way with H5P tools. Book a presentation!","breadcrumb":{"@id":"https:\/\/xoompoint.com\/en\/content-production-tools#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xoompoint.com\/en\/content-production-tools"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xoompoint.com\/en\/content-production-tools#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/xoompoint.com\/en"},{"@type":"ListItem","position":2,"name":"Content production tools"}]},{"@type":"WebSite","@id":"https:\/\/xoompoint.com\/#website","url":"https:\/\/xoompoint.com\/","name":"Xoompoint","description":"Kaikki, mit\u00e4 tarvitset digioppimiseen.","publisher":{"@id":"https:\/\/xoompoint.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xoompoint.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/xoompoint.com\/#organization","name":"Xoompoint Oy","url":"https:\/\/xoompoint.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/xoompoint.com\/#\/schema\/logo\/image\/","url":"https:\/\/xoompoint.com\/wp-content\/uploads\/2021\/12\/xoompoint-logo-black_800px.png","contentUrl":"https:\/\/xoompoint.com\/wp-content\/uploads\/2021\/12\/xoompoint-logo-black_800px.png","width":800,"height":138,"caption":"Xoompoint Oy"},"image":{"@id":"https:\/\/xoompoint.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/xoompoint\/","https:\/\/www.linkedin.com\/company\/xoompoint-corporation\/"]}]}},"_links":{"self":[{"href":"https:\/\/xoompoint.com\/en\/wp-json\/wp\/v2\/pages\/7110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xoompoint.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/xoompoint.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/xoompoint.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/xoompoint.com\/en\/wp-json\/wp\/v2\/comments?post=7110"}],"version-history":[{"count":5,"href":"https:\/\/xoompoint.com\/en\/wp-json\/wp\/v2\/pages\/7110\/revisions"}],"predecessor-version":[{"id":8527,"href":"https:\/\/xoompoint.com\/en\/wp-json\/wp\/v2\/pages\/7110\/revisions\/8527"}],"wp:attachment":[{"href":"https:\/\/xoompoint.com\/en\/wp-json\/wp\/v2\/media?parent=7110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}